{"id":8022,"date":"2024-09-30T10:41:27","date_gmt":"2024-09-30T16:41:27","guid":{"rendered":"https:\/\/conectagt.com\/?p=8022"},"modified":"2024-09-30T10:51:22","modified_gmt":"2024-09-30T16:51:22","slug":"conecta-y-su-trabajo-en-la-reduccion-del-impacto-ambiental","status":"publish","type":"post","link":"https:\/\/conectagt.com\/en\/planet\/environmental-care\/conecta-y-su-trabajo-en-la-reduccion-del-impacto-ambiental\/","title":{"rendered":"Conecta y su trabajo en la reducci\u00f3n del impacto ambiental"},"content":{"rendered":"\n<p>En Conecta, sabemos que nuestra misi\u00f3n no solo es transportar energ\u00eda, sino tambi\u00e9n cuidar de nuestro planeta y de las comunidades que nos rodean. Por eso, nos hemos comprometido a ser cada vez m\u00e1s sostenibles, reduciendo nuestra huella ambiental con acciones concretas y medibles.&nbsp;<\/p>\n\n\n\n<p>De esta manera, en 2023, logramos una impresionante reducci\u00f3n del 24% en nuestras emisiones de gases de efecto invernadero en comparaci\u00f3n con 2019, \u00a1muy por encima de la meta inicial del 2%! Este logro nos motiva a seguir innovando y buscando nuevas maneras de ser m\u00e1s amigables con el medio ambiente\u200b.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nuestros programas para reducir las emisiones de carbono<\/h2>\n\n\n\n<p>En nuestra b\u00fasqueda por un futuro m\u00e1s limpio, hemos instalado paneles solares en la Subestaci\u00f3n Pac\u00edfico l. Solo en 2023, esta iniciativa evit\u00f3 la emisi\u00f3n de 56.89 toneladas de CO\u2082, una contribuci\u00f3n significativa para el planeta\u200b. Adem\u00e1s, implementamos un programa de gesti\u00f3n de la eficiencia energ\u00e9tica que nos permite monitorear y ajustar el consumo de energ\u00eda en tiempo real.&nbsp;<\/p>\n\n\n\n<p>Gracias a estas acciones, hemos logrado cumplir nuestras metas sin necesidad de compensar emisiones con bonos de carbono\u200b.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uso eficiente de recursos en nuestras operaciones<\/h2>\n\n\n\n<p>Nos enorgullece fomentar el uso eficiente de los recursos naturales. Durante 2023, hemos realizado actividades de reciclaje en el marco de la Semana de la Sostenibilidad, recolectando y entregando 1.53 toneladas de material reciclable a proveedores especializados\u200b. Asimismo, nuestro consumo energ\u00e9tico de fuentes renovables alcanz\u00f3 los 657 GJ, contribuyendo a un consumo total de energ\u00eda interna m\u00e1s sostenible\u200b.&nbsp;<\/p>\n\n\n\n<p>Estas iniciativas reflejan nuestro compromiso con la reducci\u00f3n de residuos y la promoci\u00f3n de un entorno m\u00e1s limpio y saludable.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e1cticas sostenibles en nuestras infraestructuras energ\u00e9ticas<\/h2>\n\n\n\n<p>La sostenibilidad es un eje fundamental de nuestras operaciones, y esto se refleja en cada proyecto de infraestructura que desarrollamos. En ese sentido, durante 2023, obtuvimos la aprobaci\u00f3n de tres instrumentos ambientales por parte del Ministerio de Ambiente y Recursos Naturales (MARN) de Guatemala, lo que fortalece nuestra gesti\u00f3n ambiental y asegura el cumplimiento de las regulaciones\u200b. Adem\u00e1s, hemos finalizado el monitoreo de tres especies cr\u00edticas a fin de demostrar que no hay impacto negativo de nuestras actividades, sobre la fauna y flora local.<\/p>\n\n\n\n<p>Asimismo, a trav\u00e9s de nuestro Programa de Rescate e Investigaci\u00f3n Arqueol\u00f3gica, hemos preservado el patrimonio cultural de Guatemala al completar excavaciones en sitios arqueol\u00f3gicos afectados por nuestras operaciones. Estos esfuerzos, junto con la restauraci\u00f3n de 13.63 hect\u00e1reas de bosques mediante programas de reforestaci\u00f3n, subrayan nuestro trabajo con la conservaci\u00f3n del entorno natural\u200b.<\/p>\n\n\n\n<p>En Conecta, estamos convencidos de que es posible operar de manera eficiente y responsable, contribuyendo al bienestar de las comunidades y al cuidado del medio ambiente. Nuestra visi\u00f3n de sostenibilidad nos impulsa a seguir desarrollando e implementando iniciativas que reduzcan nuestra huella ambiental y promuevan el desarrollo sostenible en Guatemala. Seguiremos trabajando con este compromiso, convencidos de que podemos marcar la diferencia en el sector energ\u00e9tico y en la vida de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Conecta, sabemos que nuestra misi\u00f3n no solo es transportar energ\u00eda, sino tambi\u00e9n cuidar de nuestro planeta y de las comunidades que nos rodean. Por eso, nos hemos comprometido a ser cada vez m\u00e1s sostenibles, reduciendo nuestra huella ambiental con acciones concretas y medibles.&nbsp; De esta manera, en 2023, logramos una impresionante reducci\u00f3n del 24% [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":8023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[55,53],"tags":[],"class_list":["post-8022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-environmental-care","category-planet"],"_links":{"self":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/8022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/comments?post=8022"}],"version-history":[{"count":1,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/8022\/revisions"}],"predecessor-version":[{"id":8025,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/8022\/revisions\/8025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media\/8023"}],"wp:attachment":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media?parent=8022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/categories?post=8022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/tags?post=8022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}