{"id":4226,"date":"2023-04-17T15:12:59","date_gmt":"2023-04-17T21:12:59","guid":{"rendered":"https:\/\/conectagt.com\/?p=4226"},"modified":"2023-04-17T15:13:03","modified_gmt":"2023-04-17T21:13:03","slug":"el-desarrollo-nos-conecta","status":"publish","type":"post","link":"https:\/\/conectagt.com\/en\/sin-categorizar\/el-desarrollo-nos-conecta\/","title":{"rendered":"El desarrollo nos Conecta"},"content":{"rendered":"\n<p>En Conecta impulsamos el desarrollo a trav\u00e9s de nuestro trabajo energizando proyectos. Hemos alcanzado reconocimiento internacional gracias a iniciativas que transformaron la historia el\u00e9ctrica de Centroam\u00e9rica.&nbsp;<\/p>\n\n\n\n<p>Somos una empresa 100% guatemalteca que desarrolla, construye y opera sistemas de transporte de energ\u00eda; nuestro fin primordial es conectar la vida de las personas y entregar servicios de calidad con altos est\u00e1ndares t\u00e9cnicos y operacionales, por medio del desarrollo e implementaci\u00f3n de pr\u00e1cticas sostenibles de acuerdo con nuestra visi\u00f3n de sostenibilidad y compromisos con el medio ambiente.<\/p>\n\n\n\n<p>En la actualidad, Conecta administra de forma exitosa 566 kil\u00f3metros de l\u00edneas de transmisi\u00f3n el\u00e9ctrica operando, con 25 subestaciones el\u00e9ctricas energizadas. En 2022, por ejemplo, el 93% de nuestros proveedores correspond\u00eda a empresas locales.<\/p>\n\n\n\n<p>En Guatemala, hemos desarrollado diversos proyectos de transmisi\u00f3n el\u00e9ctrica, con los cuales se busca contribuir a la infraestructura de transmisi\u00f3n el\u00e9ctrica nacional actual, y as\u00ed fortalecer las oportunidades para la expansi\u00f3n de la electrificaci\u00f3n rural y\/o nuevos usuarios. En la actualidad se encuentran en desarrollo proyectos como <a href=\"https:\/\/conectagt.com\/proyectos\/subestacion-interfaz\/\">Subestaci\u00f3n Interfaz<\/a> y <a href=\"https:\/\/conectagt.com\/proyectos\/proyecto-modesto-mendez\/\">Proyecto Modesto M\u00e9ndez<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conectados con nuestros valores<\/strong><\/h2>\n\n\n\n<p>Alineados con nuestros <a href=\"https:\/\/conectagt.com\/acerca-de-conecta\/#valores-corporativos\">valores corporativos<\/a>, reafirmamos nuestro compromiso con el desarrollo a trav\u00e9s de proyectos que impactan positivamente en el crecimiento de los sitios en los cuales operamos, a trav\u00e9s de la generaci\u00f3n de empleo contratando mano de obra local y proveedores nacionales<\/p>\n\n\n\n<p>En Conecta buscamos contribuir d\u00eda a d\u00eda con el desarrollo sostenible de nuestro pa\u00eds, por medio de proyectos de transmisi\u00f3n el\u00e9ctrica, conectando la vida de las personas a trav\u00e9s del poder de la energ\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Conecta impulsamos el desarrollo a trav\u00e9s de nuestro trabajo energizando proyectos. Hemos alcanzado reconocimiento internacional gracias a iniciativas que transformaron la historia el\u00e9ctrica de Centroam\u00e9rica.&nbsp; Somos una empresa 100% guatemalteca que desarrolla, construye y opera sistemas de transporte de energ\u00eda; nuestro fin primordial es conectar la vida de las personas y entregar servicios de [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":4227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/4226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/comments?post=4226"}],"version-history":[{"count":0,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/4226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media\/4227"}],"wp:attachment":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media?parent=4226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/categories?post=4226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/tags?post=4226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}