{"id":3921,"date":"2022-10-03T12:15:27","date_gmt":"2022-10-03T18:15:27","guid":{"rendered":"https:\/\/conectagt.com\/?p=3921"},"modified":"2022-10-03T12:15:30","modified_gmt":"2022-10-03T18:15:30","slug":"el-impacto-social-que-tiene-una-mejor-iluminacion","status":"publish","type":"post","link":"https:\/\/conectagt.com\/en\/personas\/apoyo-a-la-comunidad\/el-impacto-social-que-tiene-una-mejor-iluminacion\/","title":{"rendered":"El impacto social que tiene una mejor iluminaci\u00f3n\u00a0"},"content":{"rendered":"\n<p><strong>La luz instalada en las calles de un pa\u00eds cumple con un papel importante para el desarrollo social y la seguridad.<\/strong><\/p>\n\n\n\n<p>Muchas personas salen temprano de sus casas, incluso antes del amanecer, para llegar a tiempo a sus lugares de trabajo, estudio, u otras actividades. Por otro lado, otros regresan despu\u00e9s del anochecer a sus hogares, tras una jornada laboral larga, una reuni\u00f3n, o un evento social.<\/p>\n\n\n\n<p>Es dif\u00edcil imaginar que esto fuera posible si no existiera un complejo sistema de iluminaci\u00f3n en las calles. Ser\u00eda m\u00e1s dif\u00edcil, tardado, pero sobre todo inseguro.<\/p>\n\n\n\n<p>Conecta, el equipo humano comprometido con transportar recurso energ\u00e9tico a Guatemala, mientras reduce su impacto en el planeta, sabe que el alumbrado p\u00fablico para la movilizaci\u00f3n de la poblaci\u00f3n resulta fundamental.&nbsp;<\/p>\n\n\n\n<p>Es por eso que su objetivo esencial consiste en transportar este recurso a distintas regiones del pa\u00eds, procurando abarcar la mayor cantidad de \u00e1reas posibles.<\/p>\n\n\n\n<p>Tambi\u00e9n puede interesarte leer: <a href=\"https:\/\/conectagt.com\/personas\/la-importancia-de-la-industria-de-la-energia-electrica-y-su-impacto%ef%bf%bc\/\" target=\"_blank\" rel=\"noreferrer noopener\">La importancia de la industria de la energ\u00eda el\u00e9ctrica y su impacto<\/a>.<\/p>\n\n\n\n<p>Hasta el momento, Conecta cuenta con 24 subestaciones el\u00e9ctricas y 630 kil\u00f3metros de l\u00edneas de transmisi\u00f3n a trav\u00e9s de sus instalaciones. Adem\u00e1s, ha desarrollado proyectos que buscan fortalecer la infraestructura el\u00e9ctrica existente para mejorar la calidad de la energ\u00eda en los departamentos donde opera, favoreciendo as\u00ed al alumbrado p\u00fablico de los mismos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPor qu\u00e9 es importante contar con un alumbrado p\u00fablico de calidad?<\/h3>\n\n\n\n<p>Tener una mejor iluminaci\u00f3n en las calles y las carreteras favorece a que las personas disfruten de una mejor calidad de vida, <a href=\"https:\/\/blogs.iadb.org\/energia\/es\/a-mas-luz-mas-seguridad-ciudadana\/\" target=\"_blank\" rel=\"noreferrer noopener\">y que se sientan m\u00e1s seguras al realizar distintas actividades por la noche.\u00a0<\/a><\/p>\n\n\n\n<p>Algunos de los beneficios que el alumbrado p\u00fablico brinda a la poblaci\u00f3n son:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Mejora la visibilidad del conductor sobre la ruta y las se\u00f1ales de tr\u00e1fico, disminuyendo as\u00ed los posibles accidentes nocturnos.<\/li><\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>Ayuda a que los peatones y automovilistas sean m\u00e1s conscientes de los posibles peligros.<\/li><\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\"><li>Aumenta la productividad industrial debido al incremento de la movilidad de transporte pesado en horas despu\u00e9s del anochecer.<br><\/li><li>Fomenta el turismo al permitir que los visitantes puedan gozar de todo lo que un lugar ofrece a cualquier hora del d\u00eda.<br><\/li><li>Crea un ambiente agradable para las personas que se encuentran en el \u00e1rea.<\/li><\/ol>\n\n\n\n<p>Tambi\u00e9n puede interesarte leer: <a href=\"https:\/\/conectagt.com\/continuidad-del-negocio\/la-relevancia-de-los-sistemas-de-transporte-para-la-cobertura-electrica\/\" target=\"_blank\" rel=\"noreferrer noopener\">La relevancia de los sistemas de transporte para la cobertura el\u00e9ctrica<\/a><\/p>\n\n\n\n<p>De acuerdo con <a href=\"https:\/\/urbanlabs.uchicago.edu\/projects\/crime-lights-study\" target=\"_blank\" rel=\"noreferrer noopener\">un estudio elaborado por Crime Lab, un laboratorio cient\u00edfico que hace uso de la ciencia forense,<\/a> el aumento de los niveles de iluminaci\u00f3n condujo a una reducci\u00f3n del 36% en los &#8220;cr\u00edmenes \u00edndice&#8221; en la ciudad de Nueva York.\u00a0<\/p>\n\n\n\n<p>La clave detr\u00e1s de esfuerzos similares en Guatemala es la electricidad, ya que la garant\u00eda de un suministro estable para todo el sistema permite que est\u00e9n funcionales los postes de luz, las c\u00e1maras, o cualquier otro sistema de monitoreo instalado en las ciudades, gracias al robustecimiento del Sistema Nacional Interconectado que hacen posible empresas como Conecta.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La luz instalada en las calles de un pa\u00eds cumple con un papel importante para el desarrollo social y la seguridad. Muchas personas salen temprano de sus casas, incluso antes del amanecer, para llegar a tiempo a sus lugares de trabajo, estudio, u otras actividades. Por otro lado, otros regresan despu\u00e9s del anochecer a sus [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":3922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-3921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apoyo-a-la-comunidad"],"_links":{"self":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/3921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/comments?post=3921"}],"version-history":[{"count":0,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/3921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media\/3922"}],"wp:attachment":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media?parent=3921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/categories?post=3921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/tags?post=3921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}