{"id":3918,"date":"2022-10-03T12:12:32","date_gmt":"2022-10-03T18:12:32","guid":{"rendered":"https:\/\/conectagt.com\/?p=3918"},"modified":"2022-11-09T19:37:21","modified_gmt":"2022-11-10T01:37:21","slug":"6-practicas-para-llevar-un-estilo-de-vida-personal-mas-sostenible","status":"publish","type":"post","link":"https:\/\/conectagt.com\/en\/planeta\/cuidado-ambiental\/6-practicas-para-llevar-un-estilo-de-vida-personal-mas-sostenible\/","title":{"rendered":"6 Pr\u00e1cticas para llevar un estilo de vida personal m\u00e1s sostenible"},"content":{"rendered":"\n<p><strong>Llevar un estilo de vida personal m\u00e1s sostenible es crucial para favorecer a la conservaci\u00f3n del medio ambiente.<\/strong><\/p>\n\n\n\n<p>Siguiendo el viejo refr\u00e1n que dice &#8220;saber es poder&#8221;, es crucial comprender que los h\u00e1bitos de consumo impactan en el medio ambiente. Desde la comida, hasta el tipo de transporte elegido, cuando se reduce la huella ecol\u00f3gica personal se generan efectos positivos en la naturaleza.&nbsp;<\/p>\n\n\n\n<p>Por esa raz\u00f3n es importante comprender que la huella ecol\u00f3gica de cada persona influye, y que es esencial que cada uno de los habitantes desarrolle una serie de h\u00e1bitos que ayuden a disminuirla.<\/p>\n\n\n\n<p>Tambi\u00e9n puede interesarte leer sobre: <a href=\"https:\/\/conectagt.com\/planeta\/los-esfuerzos-del-sector-del-transporte-de-energia-para-reducir-la-huella-de-carbono-en-sus-operaciones\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los esfuerzos del sector del transporte de energ\u00eda para reducir la huella de carbono en sus operaciones.<\/a><\/p>\n\n\n\n<p>Uno de los pilares fundamentales para Conecta es el cuidado ambiental. Por eso parte integral de su cultura corporativa consiste en construir un mundo eficiente, sostenible y equitativo.<\/p>\n\n\n\n<p>Conecta trabaja por un planeta m\u00e1s verde a trav\u00e9s del transporte de energ\u00eda de manera confiable, segura, e innovadora. Adem\u00e1s, la empresa apoya diversas iniciativas que impulsan a las personas a adoptar un estilo de vida personal m\u00e1s sostenible.<\/p>\n\n\n\n<p>En un contexto en el que hay un n\u00famero importante de personas que a\u00fan no ha comenzado a implementar un estilo de vida m\u00e1s sostenible por cuestiones de desinformaci\u00f3n, o bien porque creen que hacerlo podr\u00eda ser dif\u00edcil, y en ocasiones costoso, Conecta busca hacer m\u00e1s visibles las opciones para el cambio.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los h\u00e1bitos para llevar una vida sustentable<\/h2>\n\n\n\n<p>Al pensar en esos segmentos de la poblaci\u00f3n global que tienen dudas sobre c\u00f3mo cambiar sus conductas y formas de relacionarse con el medio ambiente, la<a href=\"https:\/\/www.nationalgeographic.es\/medio-ambiente\/2021\/04\/28-ideas-para-vivir-de-forma-mas-sostenible-en-el-planeta\" target=\"_blank\" rel=\"noreferrer noopener\"> Revista National Geographic,<\/a> se ha encargado de proponer algunas maneras pr\u00e1cticas para comenzar, entre las cuales se encuentran:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Comprar menos<\/h3>\n\n\n\n<p>Dos tercios de los productos que se consumen terminan convirti\u00e9ndose en residuos. Es por eso que es importante no solo buscar maneras de reutilizar o reciclar, sino tambi\u00e9n de disminuir la cantidad de productos que se adquieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Consumir m\u00e1s plantas<\/h3>\n\n\n\n<p>El consumo de alimentos provenientes de animales es una de las mayores causas de la destrucci\u00f3n de h\u00e1bitats, la contaminaci\u00f3n del agua, la deforestaci\u00f3n, y la extinci\u00f3n de la fauna. Para contrarrestar estos efectos se recomienda reducir el consumo de carne y productos l\u00e1cteos, y aumentar el consumo de productos de origen vegetal.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Reducir gasto de electricidad<\/h3>\n\n\n\n<p>Para reducir el gasto de electricidad se pueden aplicar diferentes medidas, desde utilizar bombillas de luz led y desconectar aparatos el\u00e9ctricos que no est\u00e1n siendo utilizados, hasta trabajar con fuentes de energ\u00edas renovables como la solar o e\u00f3lica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Adquirir productos que favorezcan una belleza sostenible<\/h3>\n\n\n\n<p>Los productos de cuidado personal son una de las fuentes m\u00e1s contaminantes, ya que su uso constante hace que terminen en la basura una gran cantidad de envases pl\u00e1sticos casi a diario. Afortunadamente, existen empresas cosm\u00e9ticas que han invertido en empaques que son reutilizables o m\u00e1s amigables con el medio ambiente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Pasar del papel a lo digital<\/h3>\n\n\n\n<p>Las personas pueden disminuir la cantidad de papel que utilizan digitalizando sus documentos, evitando imprimir aquellos que no son necesarios, o realizar impresiones de doble cara. Incluso, pueden solicitar desactivar la recepci\u00f3n de correspondencia en papel a diferentes empresas como bancos o medios de comunicaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Medios de transporte m\u00e1s verdes<\/h3>\n\n\n\n<p>Una de las opciones para disminuir la contaminaci\u00f3n generada por los medios de transporte es hacer uso del transporte p\u00fablico. Muchos tambi\u00e9n han comenzado a implementar el uso de la movilidad el\u00e9ctrica para disminuir su contribuci\u00f3n a la emisi\u00f3n de gases de efecto invernadero provocada por el uso de combustibles f\u00f3siles.<\/p>\n\n\n\n<p>Tambi\u00e9n puede interesarte leer:<a href=\"https:\/\/conectagt.com\/corporativo\/cuales-son-las-tendencias-mas-importantes-en-la-micromovilidad-electrica\/\" target=\"_blank\" rel=\"noreferrer noopener\"> \u00bfCu\u00e1les son las tendencias m\u00e1s importantes en la micromovilidad el\u00e9ctrica?<\/a><\/p>\n\n\n\n<p>De manera que, la adopci\u00f3n de un estilo de vida sostenible proporciona varios beneficios para la salud, promoviendo la calidad de vida, el bienestar, y el medio ambiente, lo que garantiza que cada quien hace su parte para preservar el planeta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llevar un estilo de vida personal m\u00e1s sostenible es crucial para favorecer a la conservaci\u00f3n del medio ambiente. Siguiendo el viejo refr\u00e1n que dice &#8220;saber es poder&#8221;, es crucial comprender que los h\u00e1bitos de consumo impactan en el medio ambiente. Desde la comida, hasta el tipo de transporte elegido, cuando se reduce la huella ecol\u00f3gica [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":3919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[23,17],"tags":[],"class_list":["post-3918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuidado-ambiental","category-planeta"],"_links":{"self":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/3918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/comments?post=3918"}],"version-history":[{"count":0,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/posts\/3918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media\/3919"}],"wp:attachment":[{"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/media?parent=3918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/categories?post=3918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conectagt.com\/en\/wp-json\/wp\/v2\/tags?post=3918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}